{"id":12617,"date":"2016-12-22T12:47:02","date_gmt":"2016-12-22T11:47:02","guid":{"rendered":"http:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/?p=12617"},"modified":"2026-04-16T09:41:19","modified_gmt":"2026-04-16T07:41:19","slug":"2-kapitel-vers-65","status":"publish","type":"post","link":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/2-kapitel-vers-65\/","title":{"rendered":"2. Kapitel, Vers 65"},"content":{"rendered":"<h3>Deutsche \u00dcbersetzung:<\/h3>\n<p>Nachdem (der Yogi) die Atem\u00fcbung wie beschrieben durchgef\u00fchrt hat, soll er durch das linke Nasenloch den Lebenshauch ausatmen. | (Diese Atem\u00fcbung) gleicht Dysbalancen mit Neigung zur Unstetheit, zum Aufbrausen, Tr\u00e4gheit aus und entfacht das innere Feuer.<\/p>\n<h3>Sanskrit Text:<\/h3>\n<ul>\n<li>vidhi-vat kumbhaka\u1e41 k\u1e5btv\u0101 recayed i\u1e0day\u0101nilam |<br \/>\nv\u0101ta-pitta-\u015ble\u1e63ma-hara\u1e41 \u015bar\u012br\u0101gni-vivardhanam ||65||<\/li>\n<li><span style=\"font-size: 1.5em;\">\u0935\u093f\u0927\u093f\u0935\u0924\u094d\u0915\u0941\u092e\u094d\u092d\u0915\u0902 \u0915\u0943\u0924\u094d\u0935\u093e \u0930\u0947\u091a\u092f\u0947\u0926\u093f\u0921\u092f\u093e\u0928\u093f\u0932\u092e\u094d \u0964<br \/>\n\u0935\u093e\u0924\u092a\u093f\u0924\u094d\u0924\u0936\u094d\u0932\u0947\u0937\u094d\u092e\u0939\u0930\u0902 \u0936\u0930\u0940\u0930\u093e\u0917\u094d\u0928\u093f\u0935\u093f\u0935\u0930\u094d\u0927\u0928\u092e\u094d \u0965\u096c\u096b\u0965<\/span><\/li>\n<li>vidhi vat kumbhakam kritva rechayed idayanilam |<br \/>\nvata pitta shleshma haram shariragni vivardhanam ||65||<\/li>\n<\/ul>\n<h3>Wort-f\u00fcr-Wort-\u00dcbersetzung:<\/h3>\n<ul>\n<li>vidhi-vat : vorschriftsgem\u00e4\u00df (\u201ewie die Vorschrift ist\u201c, <a title=\"Vidhivat\" href=\"https:\/\/wiki.yoga-vidya.de\/Vidhivat\">Vidhivat<\/a>)<\/li>\n<li>kumbhaka\u1e41 : (die) Atemverhaltung (<a title=\"Kumbhaka\" href=\"https:\/\/wiki.yoga-vidya.de\/Kumbhaka\">Kumbhaka<\/a>)<\/li>\n<li>k\u1e5btv\u0101 : nachdem (er) ausgef\u00fchrt hat (<a title=\"Kri\" href=\"https:\/\/wiki.yoga-vidya.de\/Kri\">k\u1e5b<\/a>)<\/li>\n<li>recayet : er atme aus (<a title=\"Rich\" href=\"https:\/\/wiki.yoga-vidya.de\/Rich\">ric<\/a>)<\/li>\n<li>i\u1e0day\u0101 : durch <a title=\"Ida\" href=\"https:\/\/wiki.yoga-vidya.de\/Ida\">Ida<\/a> (den im linken Nasenloch endenden \u201eMondkanal\u201c)<\/li>\n<li>anilam : (die) Luft (\u201eWind\u201c, <a title=\"Anila\" href=\"https:\/\/wiki.yoga-vidya.de\/Anila\">Anila<\/a>)<\/li>\n<li>v\u0101ta :\u00a0(\u00fcberm\u00e4\u00dfiges) <a title=\"Vata\" href=\"https:\/\/wiki.yoga-vidya.de\/Vata\">Vata<\/a> (\u201eWind\u201c)<\/li>\n<li>pitta : (und \u00fcberm\u00e4\u00dfiges) <a title=\"Pitta\" href=\"https:\/\/wiki.yoga-vidya.de\/Pitta\">Pitta<\/a> (\u201eGalle\u201c)<\/li>\n<li>\u015ble\u1e63ma-hara\u1e41 : (das) beseitigt (<a title=\"Hara\" href=\"https:\/\/wiki.yoga-vidya.de\/Hara\">Hara<\/a>, \u00fcberm\u00e4\u00dfigen) Schleim (<a class=\"mw-redirect\" title=\"Shleshman\" href=\"https:\/\/wiki.yoga-vidya.de\/Shleshman\">Shleshman<\/a> bzw. <a title=\"Kapha\" href=\"https:\/\/wiki.yoga-vidya.de\/Kapha\">Kapha<\/a>)<\/li>\n<li>\u015bar\u012bra : (im) K\u00f6rper (<a title=\"Sharira\" href=\"https:\/\/wiki.yoga-vidya.de\/Sharira\">Sharira<\/a>)<\/li>\n<li>agni : (des Verdauungs-)Feuers (<a title=\"Agni\" href=\"https:\/\/wiki.yoga-vidya.de\/Agni\">Agni<\/a>)<\/li>\n<li>vivardhanam : (und f\u00fchrt zur) Zunahme (<a title=\"Vivardhana\" href=\"https:\/\/wiki.yoga-vidya.de\/Vivardhana\">Vivardhana<\/a>) \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 ||65||<\/li>\n<\/ul>\n<h3>Kommentare &#8211; Audio &#8211; Video<\/h3>\n<div class=\"responsive-tabs\">\n<h2 class=\"tabtitle\">Brahmananda<\/h2>\n<div class=\"tabcontent\">\n\n<p><a href=\"https:\/\/wiki.yoga-vidya.de\/Bhastrika\" target=\"_blank\" rel=\"noopener\">Bhastrika<\/a> Kumbhaka sollte folgenderma\u00dfen ausgef\u00fchrt werden: Dr\u00fccke das linke Nasenloch mit dem Ringfinger und dem kleinen Finger, und beim rechten Nasenloch atme ein und aus, wie ein Blasebalg. Wer sich m\u00fcde f\u00fchlt, sollte <a href=\"https:\/\/wiki.yoga-vidya.de\/Kumbhaka\" target=\"_blank\" rel=\"noopener\">Kumbhaka<\/a> verrichten, wobei er durch das rechte Nasenloch einatmet und durch das linke Nasenloch ausatmet. Dann sollte er die Nasenl\u00f6cher zudr\u00fccken und dann beim rechten Nasenloch einatmen und ausatmen wie ein Blasebalg. Er sollte abwechselnd weitermachen, bis er sich m\u00fcde f\u00fchlt. Das ist eine Methode.<\/p>\n\n<\/div><h2 class=\"tabtitle\">Vishnu-devananda<\/h2>\n<div class=\"tabcontent\">\n\n<p>Nachdem er <a href=\"https:\/\/wiki.yoga-vidya.de\/Kumbhaka\" target=\"_blank\" rel=\"noopener\">Kumbhaka<\/a> den Regeln gem\u00e4\u00df ausgef\u00fchrt hat, sollte er durch das linke Nasenloch ausatmen. Das beseitigt die <a href=\"https:\/\/www.yoga-vidya.de\/de\/asana\/uebungbeschwerde.html\" target=\"_blank\" rel=\"noopener\">Beschwerden<\/a>, die vom \u00dcberma\u00df an Wind, Galle und Schleim kommen, und steigert das Verdauungsfeuer im K\u00f6rper.<\/p>\n<p>Eine andere Art der Ausf\u00fchrung ist, das linke Nasenloch zu schlie\u00dfen und so viel wie m\u00f6glich mit dem rechten Nasenloch einzuatmen, und dann ganz langsam durch das linke Nasenloch auszuatmen. Das sollte einige Male gemacht werden, und wenn er sich dann m\u00fcde f\u00fchlen sollte, sollte er Kumbhaka durchf\u00fchren und durch die <a href=\"https:\/\/wiki.yoga-vidya.de\/Ida\" target=\"_blank\" rel=\"noopener\">Ida<\/a> <a href=\"https:\/\/wiki.yoga-vidya.de\/Nadi\" target=\"_blank\" rel=\"noopener\">Nadi<\/a> ausatmen.<\/p>\n\n<\/div><h2 class=\"tabtitle\">Sukadev<\/h2>\n<div class=\"tabcontent\">\n\n<p>65. Nachdem er <a href=\"https:\/\/wiki.yoga-vidya.de\/Kumbhaka\">Kumbhaka<\/a> den Regeln gem\u00e4\u00df ausgef\u00fchrt hat,<\/p>\n<p>d.h. mit Mula-, Uddhiyana- und Jalandhara Bhanda<\/p>\n<p>\u2013 sollte er durch das linke Nasenloch ausatmen.<\/p>\n<p>Feste ein- und ausatmen. Nach dem letzten Ausatmen rechts einatmen, anhalten, wer nicht mehr halten kann links ausatmen. Man kann dabei beim Anhalten die Finger an der Nase halten oder auch absetzen.<\/p>\n<p>\u2013 Das beseitigt die Beschwerden, die vom \u00dcberma\u00df an Wind, Galle und Schleim \u2013<a href=\"https:\/\/www.yoga-vidya.de\/ayurveda\/ayurveda-typen\/ayurveda-typen-vata.html\">Vata<\/a>, Pita und <a href=\"https:\/\/www.yoga-vidya.de\/ayurveda\/ayurveda-typen\/ayurveda-typen-kapha.html\">Kapha<\/a><\/p>\n<p>\u2013 kommen, und steigert das Verdauungsfeuer<\/p>\n<p><a href=\"https:\/\/wiki.yoga-vidya.de\/Agni\">Agni<\/a><\/p>\n<p>\u2013 im K\u00f6rper.<\/p>\n<p>Also Bhastrika harmonisiert alle Lebensenergien. Und dadurch, dass die Lebensenergien harmonisiert werden, werden auch die <a href=\"https:\/\/www.yoga-vidya.de\/ayurveda\/ayurveda-typen.html\">Doshas<\/a> harmonisiert, und dadurch dass diese harmonisiert werden, kommt auch Gesundheit. Und ich kenne sogar eine Frau, die hat gesagt, sie ist eine fortgeschrittene Form von Krebs, die als unheilbar diagnostiziert wurde, durch intensives <a href=\"https:\/\/www.yoga-vidya.de\/Yoga--Artikel\/Art-Artikel\/Art_Pranayama.html\">Pranayama<\/a>, insbesondere Bhastrika wieder losgeworden. Sie war schon aufgegeben worden, man hat gesagt, man kann nicht mehr operieren. Chemo und alles andere war schon mal versucht worden, es hat nichts genutzt. Und da hat sie gesagt, anstatt jetzt den Rest ihres Lebens, was noch ein halbes Jahr gewesen sein sollte, anstatt den jetzt nur noch mit \u00c4rzten zu verbringen, macht sie einfach so viel Pranayama wie m\u00f6glich. Und irgendwie hat sie gemerkt, Bhastrika ist f\u00fcr sie besonders gut. Da hat sie zehn Runden Bhastrika dreimal am Tag gemacht, nach dem <a href=\"https:\/\/www.yoga-vidya.de\/de\/asana\/kapalabhati.html\">Kapalabhati<\/a> und der Wechselatmung. Und nach einem viertel Jahr war der Krebs g\u00e4nzlich verschwunden. Und die Dame war sechzig, als sie mir das erz\u00e4hlt hat, mit f\u00fcnfzig hat sie dieses intensive Pranayama gemacht. Also das Pranayama hat eine Vielzahl von Wirkungen. Also es ist durchaus was, wenn man auch mal gr\u00f6\u00dfere Schwierigkeiten hat, bevor man sich jetzt mehrere Wochen oder Monate in die H\u00e4nde von \u00c4rzten begibt, zu \u00fcberlegen, ob man vielleicht sich nicht mehrere Wochen in die H\u00e4nde vom reinen <a href=\"https:\/\/www.yoga-vidya.de\/prana.html\">Prana<\/a> begibt durch intensives Pranayama. Es ist auch eine paradoxe Geschichte. Wenn jemand sagt: \u201eIch mach jetzt ein paar Wochen sechzehn Stunden am Tag Pranayama\u201c, das gilt als extrem. Wenn jemand sagt: \u201eIch gehe jetzt ins Krankenhaus, lasse mich operieren und muss ein paar Monate nachsorgen,\u201c das gilt als normal. Oder Chemotherapie. Wobei ich jetzt nicht davon abrate. Also wenn mich jemand hier fragt, ob er Chemotherapie machen sollte, im Normalfall, aus verschiedenen Gr\u00fcnden sage ich dann, er soll die Meinung von verschiedenen \u00c4rzten einholen und dann letztlich auch nach medizinischen Sachen entscheiden. Aber wenn\u2019s nicht so dringend ist \u2013 ich kannte jemand mit einer Prostataoperation. Da hab ich ihn gefragt, ob er\u2019s zwo Wochen noch rausz\u00f6gern kann. Er hat mit dem Arzt gesprochen, ja, zwo Wochen, einen Monat ginge auch noch. Da habe ich ihm gesagt, er solle jeden Tag 108 Mal OM Tryambhakam sagen, und er solle viel <a href=\"https:\/\/www.yoga-vidya.de\/Yoga--Artikel\/Art-Artikel\/Art_Pranayama.html\">Pranayama<\/a> machen. Bei ihm hab ich gesp\u00fcrt, das w\u00e4re jetzt gerade gut f\u00fcr ihn. Der Arzt hat aber gesagt, einen festen Termin machen wir trotzdem aus, noch mal verschieben wir nicht. Und der Termin stand dann also fest. Routinem\u00e4\u00dfig werden vor der Operation werden die Blutwerte abgenommen. Und der Arzt hat sie zwomal abgenommen und zwomal untersuchen lassen. Und die PSA-Werte, oder wie die hei\u00dfen, sind zum g\u00e4nzlich Normalen zur\u00fcckgegangen, und die n\u00e4chste Biopsie hat gezeigt, dass alles wieder in Ordnung ist. Also es gibt solche F\u00e4lle, aber es n\u00fctzt nicht immer. Ich kannte auch jemand, der hatte Krebs und hat alles M\u00f6gliche probiert, der ist dann trotzdem gestorben.<\/p>\n<p>Frage: Wodurch werden Granthis beseitigt ? <a href=\"https:\/\/www.yoga-vidya.de\/Bilder\/Galerien\/Brahma.html\">Brahma<\/a>-Granthi,<a href=\"https:\/\/www.yoga-vidya.de\/Bilder\/Galerien\/Vishnu.html\">Vishnu<\/a>-Granthi, Rudhra-Granthi ( <a href=\"https:\/\/www.yoga-vidya.de\/Bilder\/Galerien\/Shivatext.html\">Shiva<\/a>-Granthi) (S. Kap 3, Vers 2)<\/p>\n<p>Gut, bis zu einem gewissen Grad k\u00f6nnen wir an den Granthis arbeiten durch Pranayama, und dann hei\u00dft es, dass gerade Bhastrika-Pranayama die Granthis durchst\u00f6\u00dft. Das beschreibt er im 67. Vers. Aber man kann jetzt nat\u00fcrlich nicht sagen, dass man alle Grobstofflichkeit durch Bhastrika \u00fcberwindet und sein Ego auch, das w\u00e4re zu einfach. Dann br\u00e4uchten wir nur noch von morgens bis abends Bhastrika zu machen, und wenn wir das ausreichend lange gemacht haben, erreichen wir die Selbstverwirklichung. Leider ist dem nicht so. Wir m\u00fcssen nat\u00fcrlich Brahma-Granthi auch \u00fcberwinden \u00fcber <a href=\"https:\/\/www.yoga-vidya.de\/de\/asana\">Asanas<\/a>, \u00fcber <a href=\"https:\/\/www.yoga-vidya.de\/meditation.html\">Meditation<\/a>. Alles das arbeitet daran, unser Wesen zu verfeinern. Und wir d\u00fcrfen dabei auch nicht die <a href=\"https:\/\/www.yoga-vidya.de\/Bilder\/Galerien\/Konfuzius.html\">Muladhara<\/a>-Ebene au\u00dfer Acht lassen. N\u00e4mlich sich im t\u00e4glichen <a href=\"https:\/\/www.yoga-vidya.de\/gemeinschaft\/Lebensgemeinschaft.html\">Leben<\/a> zurechtzufinden und in der Lage zu sein, sein Leben zu leben in Beruf und Familie. Auch das ist eine Grundlage daf\u00fcr, dass wir Brahma-Granthi dauerhaft durchsto\u00dfen und nicht, dass wir dann immer wieder von der physischen Welt zur\u00fcckgezogen werden, da wir sie vorher vernachl\u00e4ssigt haben. Gut, und Vishnu-Granthi wird nat\u00fcrlich \u00fcberwunden durch selbstloses Dienen, durch Mantrasingen, durch <a href=\"https:\/\/wiki.yoga-vidya.de\/Hingabe\">Hingabe<\/a>, und so weiter. Und Pranayama spielt auch eine Rolle. Und Rudhra-Granthi, wodurch wird der \u00fcberwunden? Durch g\u00f6ttliche <a href=\"https:\/\/wiki.yoga-vidya.de\/Gnade\">Gnade<\/a> und <a href=\"https:\/\/www.yoga-vidya.de\/Yoga--Artikel\/Art-Artikel\/art_samadhi.html\">Samadhi<\/a>.<\/p>\n<p>Das ist auch noch eine Sache, die auch ayurvedisch interessant ist. All diese \u00dcbungen, von denen der Swatmarama sagt, dass er das <a href=\"https:\/\/wiki.yoga-vidya.de\/Agni\">Agni<\/a>, das Verdauungsfeuer erh\u00f6ht. Dazu geh\u00f6rte Paschimottanasana, dazu geh\u00f6rte Matsyendrasana, Mayurasana und jetzt Bhastrika.<\/p>\n<p>Weiter schreibt er \u00fcber die <a href=\"https:\/\/www.yoga-vidya.de\/yoga-anfaenger\/wirkung-von-yoga.html\">Wirkung<\/a> von Bhastrika:<\/p>\n<p>\n<\/div><h2 class=\"tabtitle\">Audio<\/h2>\n<div class=\"tabcontent\">\n<br \/>\n<div class=\"powerpress_player\" id=\"powerpress_player_7331\"><audio class=\"wp-audio-shortcode\" id=\"audio-12617-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/jkv3wg.podcaster.de\/download\/138_Hathayoga_Pradipika_2_Kap-_65.mp3?_=1\" \/><a href=\"https:\/\/jkv3wg.podcaster.de\/download\/138_Hathayoga_Pradipika_2_Kap-_65.mp3\">https:\/\/jkv3wg.podcaster.de\/download\/138_Hathayoga_Pradipika_2_Kap-_65.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"https:\/\/jkv3wg.podcaster.de\/download\/138_Hathayoga_Pradipika_2_Kap-_65.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/?powerpress_pinw=12617-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"https:\/\/jkv3wg.podcaster.de\/download\/138_Hathayoga_Pradipika_2_Kap-_65.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"138_Hathayoga_Pradipika_2_Kap-_65.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p><\/p>\n\n<\/div><h2 class=\"tabtitle\">Video<\/h2>\n<div class=\"tabcontent\">\n\n<p>.\/.<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche \u00dcbersetzung: Nachdem (der Yogi) die Atem\u00fcbung wie beschrieben durchgef\u00fchrt hat, soll er durch das linke Nasenloch den Lebenshauch ausatmen. | (Diese Atem\u00fcbung) gleicht Dysbalancen mit Neigung zur Unstetheit, zum Aufbrausen, Tr\u00e4gheit aus und entfacht das innere Feuer. Sanskrit Text: vidhi-vat kumbhaka\u1e41 k\u1e5btv\u0101 recayed i\u1e0day\u0101nilam | v\u0101ta-pitta-\u015ble\u1e63ma-hara\u1e41 \u015bar\u012br\u0101gni-vivardhanam ||65|| \u0935\u093f\u0927\u093f\u0935\u0924\u094d\u0915\u0941\u092e\u094d\u092d\u0915\u0902 \u0915\u0943\u0924\u094d\u0935\u093e \u0930\u0947\u091a\u092f\u0947\u0926\u093f\u0921\u092f\u093e\u0928\u093f\u0932\u092e\u094d \u0964 \u0935\u093e\u0924\u092a\u093f\u0924\u094d\u0924\u0936\u094d\u0932\u0947\u0937\u094d\u092e\u0939\u0930\u0902 \u0936\u0930\u0940\u0930\u093e\u0917\u094d\u0928\u093f\u0935\u093f\u0935\u0930\u094d\u0927\u0928\u092e\u094d &hellip; <a href=\"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/2-kapitel-vers-65\/\" class=\"more-link\"><span class=\"screen-reader-text\">2. Kapitel, Vers 65<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[438,419],"tags":[145],"class_list":["post-12617","post","type-post","status-publish","format-standard","hentry","category-2-kapitel-verse-61-70","category-pranayama-kriyas","tag-2-kapitel-65-vers"],"_links":{"self":[{"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/posts\/12617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/comments?post=12617"}],"version-history":[{"count":5,"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/posts\/12617\/revisions"}],"predecessor-version":[{"id":16398,"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/posts\/12617\/revisions\/16398"}],"wp:attachment":[{"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/media?parent=12617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/categories?post=12617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schriften.yoga-vidya.de\/hatha-yoga-pradipika\/wp-json\/wp\/v2\/tags?post=12617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}